{"id":2744,"date":"2024-08-16T21:14:24","date_gmt":"2024-08-16T21:14:24","guid":{"rendered":"https:\/\/www.esculturasanjose.com\/?post_type=product&#038;p=2744"},"modified":"2024-10-30T19:28:25","modified_gmt":"2024-10-30T19:28:25","slug":"virgen-de-la-misericordia-our-lady-of-mercy-120cm-47inch","status":"publish","type":"product","link":"https:\/\/www.esculturasanjose.com\/en\/product\/virgen-de-la-misericordia-our-lady-of-mercy-120cm-47inch\/","title":{"rendered":"Virgen de la Misericordia \u2013 Our Lady Of Mercy 120cm 47inch"},"content":{"rendered":"<p><strong>\u2022 DETALLE Y CALIDAD:<\/strong>\u00a0Solo lo mejor en t\u00e9rminos de calidad, nuestras figuras son realizadas teniendo mucho cuidado en los gustos y detalles de las expresiones faciales y el colorido. Cada pieza est\u00e1 pintada a mano hasta el m\u00e1s m\u00ednimo detalle.<\/p>\n<p><strong>\u2022 MATERIALES:<\/strong>\u00a0Hechas con una mezcla de resina poli\u00e9ster, nuestras esculturas de m\u00e1s de 60cm son laminadas, lo que las hace lo suficientemente livianas para transportarlas y exhibirlas f\u00e1cilmente, pero est\u00e1n hechas para ser fuertes y duraderas. Las im\u00e1genes peque\u00f1as son fundidas rellenas. Cada uno est\u00e1 pintado a mano con pintura fina a base de oleo.<\/p>","protected":false},"excerpt":{"rendered":"<p>CM 120<\/p>\n<p>INCH 47<\/p>\n<p>COD 15623<\/p>\n<p>Informaci\u00f3n: +593 98 919 6231<\/p>","protected":false},"featured_media":2745,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[53],"product_tag":[133,92,79],"_links":{"self":[{"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/product\/2744"}],"collection":[{"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/comments?post=2744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/media\/2745"}],"wp:attachment":[{"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/media?parent=2744"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/product_cat?post=2744"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.esculturasanjose.com\/en\/wp-json\/wp\/v2\/product_tag?post=2744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}